{"id":11467,"date":"2026-07-15T11:38:06","date_gmt":"2026-07-15T14:38:06","guid":{"rendered":"https:\/\/canadiancraftsfederation.ca\/?p=11467"},"modified":"2026-07-15T11:51:30","modified_gmt":"2026-07-15T14:51:30","slug":"pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026","status":"publish","type":"post","link":"https:\/\/canadiancraftsfederation.ca\/fr\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\/","title":{"rendered":"Pour un meilleur support des m\u00e9tiers d&rsquo;art : Recommandations pour le budget f\u00e9d\u00e9ral de 2026"},"content":{"rendered":"\n<p>Pour l\u2019ann\u00e9e 2026, la F\u00e9d\u00e9ration canadienne des m\u00e9tiers d\u2019art (FCMA\/CCF), en collaboration avec les conseils provinciaux des m\u00e9tiers d\u2019art et organismes affili\u00e9s, se pr\u00e9sente ici \u00e0 titre de f\u00e9d\u00e9ration d\u2019organisations afin d\u2019\u00e9laborer ses Recommandations pr\u00e9-budg\u00e9taires destin\u00e9es au ministre f\u00e9d\u00e9ral des Finances. L\u2019objectif de la FCMA\/CCF est de se faire entendre \u00e0 travers une voix unie et distinctive sur les enjeux majeurs qui touchent les secteurs des arts visuels et des m\u00e9tiers d\u2019art dans le contexte politique et \u00e9conomique auquel nous faisons face. Notre engagement dans le processus de consultations pr\u00e9-budg\u00e9taires du minist\u00e8re des Finances joue un r\u00f4le essentiel de repr\u00e9sentation et de d\u00e9fense des int\u00e9r\u00eats de notre secteur \u00e0 l\u2019\u00e9chelle nationale.<\/p>\n\n\n\n<p>Le compte -rendu de la FCMA\/CCF en vue des consultations pr\u00e9budg\u00e9taires de 2026 met de l\u2019avant cinq recommandations prioritaires, en phase avec les r\u00e9alit\u00e9s auxquelles sont confront\u00e9s les acteurs canadiens des communaut\u00e9s artistiques et des m\u00e9tiers d\u2019art :<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>R\u00e9viser et adapter les \u00e9ch\u00e9anciers, les crit\u00e8res d\u2019admissibilit\u00e9 et les niveaux de financement des programmes f\u00e9d\u00e9raux existants et propos\u00e9s dans les domaines des arts, de la culture, du tourisme et de l\u2019exportation.<\/li><li>Augmenter le financement de base des organismes de services aux arts (OSA) afin qu\u2019ils puissent mieux soutenir leurs communaut\u00e9s et maintenir en poste du personnel qualifi\u00e9.<\/li><li>R\u00e9duire les barri\u00e8res commerciales et investir dans la diversification des march\u00e9s du secteur cr\u00e9atif. Diminuer les co\u00fbts li\u00e9s au commerce pour les producteur.ice.s des en m\u00e9tiers d\u2019art canadiens en s\u2019attaquant aux tarifs douaniers et aux droits sur les mat\u00e9riaux, en mettant en place des programmes f\u00e9d\u00e9raux cibl\u00e9s pour soutenir le d\u00e9veloppement des exportations, la diversification des march\u00e9s et les besoins sp\u00e9cifiques au secteur d\u2019affaires.<\/li><li>Consacrer un minimum de 1 % des d\u00e9penses totales du gouvernement du Canada aux arts, \u00e0 la culture et au patrimoine. En atteignant cet objectif au cours de l\u2019exercice financier de 2026-2027, le gouvernement devrait augmenter ses investissements \u00e0 hauteur de 270 millions de dollars.<\/li><li>Mettre en place un programme d\u2019assurance-emploi adapt\u00e9 aux r\u00e9alit\u00e9s des travailleuses et travailleurs des secteurs des arts et de la culture.<\/li><\/ol>\n\n\n\n<p>Le compte -rendu en vue de ces consultations pr\u00e9-budg\u00e9taires de 2026 accorde donc une attention particuli\u00e8re aux politiques commerciales actuelles, \u00e0 la protection sociale des artisan\u00b7e\u00b7s , \u00e0 l\u2019augmentation des financements structurels de base pour les organismes ainsi qu\u2019\u00e0 l\u2019am\u00e9lioration des programmes de financement par projet.<\/p>\n\n\n\n<p>En effet, les revenus moyens des artiste\u00b7e\u00b7s visuel\u00b7le\u00b7s et des artisan\u00b7e\u00b7s sont inf\u00e9rieurs de plus de 50 % \u00e0 ceux de l\u2019ensemble de la population active canadienne, une r\u00e9alit\u00e9 \u00e9conomique qui limite leur capacit\u00e9 \u00e0 maintenir leurs activit\u00e9s professionnelles. Cette situation est aggrav\u00e9e par les politiques tarifaires actuelles et par l\u2019insuffisance des mesures visant \u00e0 r\u00e9duire les barri\u00e8res commerciales qui affectent de mani\u00e8re disproportionn\u00e9e l\u2019activit\u00e9 \u00e9conomique du secteur des m\u00e9tiers d\u2019art. Nos recommandations soulignent \u00e9galement la n\u00e9cessit\u00e9 de prioriser le soutien au fonctionnement des organismes artistiques, en particulier les organismes de services aux arts par une augmentation du financement de base et par l\u2019adaptation des calendriers de d\u00e9p\u00f4t des demandes de financement aux r\u00e9alit\u00e9s de l\u2019exercice financier et \u00e0 ses \u00e9ch\u00e9ances.<\/p>\n\n\n\n<p>Dans un secteur confront\u00e9 \u00e0 des d\u00e9fis \u00e9conomiques, sociaux et structurels importants, la F\u00e9d\u00e9ration canadienne des m\u00e9tiers d\u2019art recommande donc que le gouvernement du Canada consacre au minimum 1 % de ses d\u00e9penses totales aux arts, \u00e0 la culture et au patrimoine, reconnaissant ainsi le r\u00f4le fondamental des travailleuses et travailleurs culturels dans la vie \u00e9conomique et sociale du pays.<\/p>\n\n\n\n<p>La FCMA\/CCF encourage l\u2019ensemble de ses membres et de ses organisations affili\u00e9es \u00e0 transmettre ces recommandations pr\u00e9-budg\u00e9taires aux <a href=\"https:\/\/www.ourcommons.ca\/members\/fr\/search#\">d\u00e9put\u00e9\u00b7e\u00b7s f\u00e9d\u00e9raux ainsi qu\u2019aux ministres provinciaux et territoriaux concern\u00e9s<\/a>, en s\u2019appuyant sur les priorit\u00e9s d\u00e9fendues par la F\u00e9d\u00e9ration dans ses recommandations publiques. La diffusion d\u2019un message commun reste essentielle pour influencer les orientations du prochain <a href=\"https:\/\/canadiancraftsfederation.ca\/wp-content\/uploads\/2026\/07\/2026-budget-recommendations-French-web.pdf\">budget f\u00e9d\u00e9ral<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour l\u2019ann\u00e9e 2026, la F\u00e9d\u00e9ration canadienne des m\u00e9tiers d\u2019art (FCMA\/CCF), en collaboration avec les conseils provinciaux des m\u00e9tiers d\u2019art et organismes affili\u00e9s, se pr\u00e9sente ici \u00e0 titre de f\u00e9d\u00e9ration d\u2019organisations&#8230;<\/p>\n","protected":false},"author":6,"featured_media":11479,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-11467","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Pour l\u2019ann\u00e9e 2026, la F\u00e9d\u00e9ration canadienne des m\u00e9tiers d\u2019art (FCMA\/CCF), en collaboration avec les conseils provinciaux des m\u00e9tiers d\u2019art et organismes affili\u00e9s, se pr\u00e9sente ici \u00e0 titre de f\u00e9d\u00e9ration d\u2019organisations afin d\u2019\u00e9laborer ses Recommandations pr\u00e9-budg\u00e9taires destin\u00e9es au ministre f\u00e9d\u00e9ral des Finances. L\u2019objectif de la FCMA\/CCF est de se faire entendre \u00e0 travers une voix unie\" \/>\n\t<meta name=\"robots\" content=\"noindex, max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Lauren Polchies\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/canadiancraftsfederation.ca\/fr\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Canadian Crafts Federation \u2022 National Arts Service Organization\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Pour un meilleur support des m\u00e9tiers d\u2019art : Recommandations pour le budget f\u00e9d\u00e9ral de 2026 \u2022 Canadian Crafts Federation\" \/>\n\t\t<meta property=\"og:description\" content=\"Pour l\u2019ann\u00e9e 2026, la F\u00e9d\u00e9ration canadienne des m\u00e9tiers d\u2019art (FCMA\/CCF), en collaboration avec les conseils provinciaux des m\u00e9tiers d\u2019art et organismes affili\u00e9s, se pr\u00e9sente ici \u00e0 titre de f\u00e9d\u00e9ration d\u2019organisations afin d\u2019\u00e9laborer ses Recommandations pr\u00e9-budg\u00e9taires destin\u00e9es au ministre f\u00e9d\u00e9ral des Finances. L\u2019objectif de la FCMA\/CCF est de se faire entendre \u00e0 travers une voix unie\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/canadiancraftsfederation.ca\/fr\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/canadiancraftsfederation.ca\/wp-content\/uploads\/2023\/07\/Form-Banner-2023.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/canadiancraftsfederation.ca\/wp-content\/uploads\/2023\/07\/Form-Banner-2023.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"6667\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1667\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-07-15T14:38:06+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-15T14:51:30+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/ccffcma\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@ccffcma\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Pour un meilleur support des m\u00e9tiers d\u2019art : Recommandations pour le budget f\u00e9d\u00e9ral de 2026 \u2022 Canadian Crafts Federation\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Pour l\u2019ann\u00e9e 2026, la F\u00e9d\u00e9ration canadienne des m\u00e9tiers d\u2019art (FCMA\/CCF), en collaboration avec les conseils provinciaux des m\u00e9tiers d\u2019art et organismes affili\u00e9s, se pr\u00e9sente ici \u00e0 titre de f\u00e9d\u00e9ration d\u2019organisations afin d\u2019\u00e9laborer ses Recommandations pr\u00e9-budg\u00e9taires destin\u00e9es au ministre f\u00e9d\u00e9ral des Finances. L\u2019objectif de la FCMA\/CCF est de se faire entendre \u00e0 travers une voix unie\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@ccffcma\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/canadiancraftsfederation.ca\/wp-content\/uploads\/2023\/07\/Form-Banner-2023.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\\\/#blogposting\",\"name\":\"Pour un meilleur support des m\\u00e9tiers d\\u2019art : Recommandations pour le budget f\\u00e9d\\u00e9ral de 2026 \\u2022 Canadian Crafts Federation\",\"headline\":\"Pour un meilleur support des m\\u00e9tiers d&rsquo;art : Recommandations pour le budget f\\u00e9d\\u00e9ral de 2026\",\"author\":{\"@id\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/author\\\/lauren-polchies\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/banner-page2-scaled.png\",\"width\":2560,\"height\":830},\"datePublished\":\"2026-07-15T11:38:06-03:00\",\"dateModified\":\"2026-07-15T11:51:30-03:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\\\/#webpage\"},\"articleSection\":\"Non classifi\\u00e9(e), Facultatif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/category\\\/non-classifiee\\\/#listItem\",\"name\":\"Non classifi\\u00e9(e)\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/category\\\/non-classifiee\\\/#listItem\",\"position\":2,\"name\":\"Non classifi\\u00e9(e)\",\"item\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/category\\\/non-classifiee\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\\\/#listItem\",\"name\":\"Pour un meilleur support des m\\u00e9tiers d&rsquo;art : Recommandations pour le budget f\\u00e9d\\u00e9ral de 2026\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\\\/#listItem\",\"position\":3,\"name\":\"Pour un meilleur support des m\\u00e9tiers d&rsquo;art : Recommandations pour le budget f\\u00e9d\\u00e9ral de 2026\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/category\\\/non-classifiee\\\/#listItem\",\"name\":\"Non classifi\\u00e9(e)\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/#organization\",\"name\":\"Canadian Crafts Federation | F\\u00e9d\\u00e9ration canadienne des m\\u00e9tiers d'art\",\"description\":\"National Arts Service Organization\",\"url\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/CCF-Logo.jpg\",\"@id\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\\\/#organizationLogo\",\"width\":2121,\"height\":1032},\"image\":{\"@id\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/ccffcma\",\"https:\\\/\\\/twitter.com\\\/ccffcma\",\"https:\\\/\\\/instagram.com\\\/ccffcma\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ccffcma\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/author\\\/lauren-polchies\\\/#author\",\"url\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/author\\\/lauren-polchies\\\/\",\"name\":\"Lauren Polchies\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c56c5de0808a6ce810e7278ed483a7d2ff1ebfcca55d33876311981c423363c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Lauren Polchies\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\\\/#webpage\",\"url\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\\\/\",\"name\":\"Pour un meilleur support des m\\u00e9tiers d\\u2019art : Recommandations pour le budget f\\u00e9d\\u00e9ral de 2026 \\u2022 Canadian Crafts Federation\",\"description\":\"Pour l\\u2019ann\\u00e9e 2026, la F\\u00e9d\\u00e9ration canadienne des m\\u00e9tiers d\\u2019art (FCMA\\\/CCF), en collaboration avec les conseils provinciaux des m\\u00e9tiers d\\u2019art et organismes affili\\u00e9s, se pr\\u00e9sente ici \\u00e0 titre de f\\u00e9d\\u00e9ration d\\u2019organisations afin d\\u2019\\u00e9laborer ses Recommandations pr\\u00e9-budg\\u00e9taires destin\\u00e9es au ministre f\\u00e9d\\u00e9ral des Finances. L\\u2019objectif de la FCMA\\\/CCF est de se faire entendre \\u00e0 travers une voix unie\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/author\\\/lauren-polchies\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/author\\\/lauren-polchies\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/banner-page2-scaled.png\",\"@id\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\\\/#mainImage\",\"width\":2560,\"height\":830},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\\\/#mainImage\"},\"datePublished\":\"2026-07-15T11:38:06-03:00\",\"dateModified\":\"2026-07-15T11:51:30-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/\",\"name\":\"Canadian Crafts Federation | F\\u00e9d\\u00e9ration canadiennes des m\\u00e9tiers d'art\",\"alternateName\":\"CCF\\\/FCMA\",\"description\":\"National Arts Service Organization\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/canadiancraftsfederation.ca\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Pour un meilleur support des m\u00e9tiers d\u2019art : Recommandations pour le budget f\u00e9d\u00e9ral de 2026 \u2022 Canadian Crafts Federation","description":"Pour l\u2019ann\u00e9e 2026, la F\u00e9d\u00e9ration canadienne des m\u00e9tiers d\u2019art (FCMA\/CCF), en collaboration avec les conseils provinciaux des m\u00e9tiers d\u2019art et organismes affili\u00e9s, se pr\u00e9sente ici \u00e0 titre de f\u00e9d\u00e9ration d\u2019organisations afin d\u2019\u00e9laborer ses Recommandations pr\u00e9-budg\u00e9taires destin\u00e9es au ministre f\u00e9d\u00e9ral des Finances. L\u2019objectif de la FCMA\/CCF est de se faire entendre \u00e0 travers une voix unie","canonical_url":"https:\/\/canadiancraftsfederation.ca\/fr\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\/","robots":"noindex, max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/canadiancraftsfederation.ca\/fr\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\/#blogposting","name":"Pour un meilleur support des m\u00e9tiers d\u2019art : Recommandations pour le budget f\u00e9d\u00e9ral de 2026 \u2022 Canadian Crafts Federation","headline":"Pour un meilleur support des m\u00e9tiers d&rsquo;art : Recommandations pour le budget f\u00e9d\u00e9ral de 2026","author":{"@id":"https:\/\/canadiancraftsfederation.ca\/fr\/author\/lauren-polchies\/#author"},"publisher":{"@id":"https:\/\/canadiancraftsfederation.ca\/fr\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/canadiancraftsfederation.ca\/wp-content\/uploads\/2026\/07\/banner-page2-scaled.png","width":2560,"height":830},"datePublished":"2026-07-15T11:38:06-03:00","dateModified":"2026-07-15T11:51:30-03:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/canadiancraftsfederation.ca\/fr\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\/#webpage"},"isPartOf":{"@id":"https:\/\/canadiancraftsfederation.ca\/fr\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\/#webpage"},"articleSection":"Non classifi\u00e9(e), Facultatif"},{"@type":"BreadcrumbList","@id":"https:\/\/canadiancraftsfederation.ca\/fr\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/canadiancraftsfederation.ca\/fr\/#listItem","position":1,"name":"Home","item":"https:\/\/canadiancraftsfederation.ca\/fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/canadiancraftsfederation.ca\/fr\/category\/non-classifiee\/#listItem","name":"Non classifi\u00e9(e)"}},{"@type":"ListItem","@id":"https:\/\/canadiancraftsfederation.ca\/fr\/category\/non-classifiee\/#listItem","position":2,"name":"Non classifi\u00e9(e)","item":"https:\/\/canadiancraftsfederation.ca\/fr\/category\/non-classifiee\/","nextItem":{"@type":"ListItem","@id":"https:\/\/canadiancraftsfederation.ca\/fr\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\/#listItem","name":"Pour un meilleur support des m\u00e9tiers d&rsquo;art : Recommandations pour le budget f\u00e9d\u00e9ral de 2026"},"previousItem":{"@type":"ListItem","@id":"https:\/\/canadiancraftsfederation.ca\/fr\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/canadiancraftsfederation.ca\/fr\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\/#listItem","position":3,"name":"Pour un meilleur support des m\u00e9tiers d&rsquo;art : Recommandations pour le budget f\u00e9d\u00e9ral de 2026","previousItem":{"@type":"ListItem","@id":"https:\/\/canadiancraftsfederation.ca\/fr\/category\/non-classifiee\/#listItem","name":"Non classifi\u00e9(e)"}}]},{"@type":"Organization","@id":"https:\/\/canadiancraftsfederation.ca\/fr\/#organization","name":"Canadian Crafts Federation | F\u00e9d\u00e9ration canadienne des m\u00e9tiers d'art","description":"National Arts Service Organization","url":"https:\/\/canadiancraftsfederation.ca\/fr\/","logo":{"@type":"ImageObject","url":"https:\/\/canadiancraftsfederation.ca\/wp-content\/uploads\/2023\/02\/CCF-Logo.jpg","@id":"https:\/\/canadiancraftsfederation.ca\/fr\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\/#organizationLogo","width":2121,"height":1032},"image":{"@id":"https:\/\/canadiancraftsfederation.ca\/fr\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/ccffcma","https:\/\/twitter.com\/ccffcma","https:\/\/instagram.com\/ccffcma","https:\/\/www.linkedin.com\/company\/ccffcma\/"]},{"@type":"Person","@id":"https:\/\/canadiancraftsfederation.ca\/fr\/author\/lauren-polchies\/#author","url":"https:\/\/canadiancraftsfederation.ca\/fr\/author\/lauren-polchies\/","name":"Lauren Polchies","image":{"@type":"ImageObject","@id":"https:\/\/canadiancraftsfederation.ca\/fr\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/9c56c5de0808a6ce810e7278ed483a7d2ff1ebfcca55d33876311981c423363c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Lauren Polchies"}},{"@type":"WebPage","@id":"https:\/\/canadiancraftsfederation.ca\/fr\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\/#webpage","url":"https:\/\/canadiancraftsfederation.ca\/fr\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\/","name":"Pour un meilleur support des m\u00e9tiers d\u2019art : Recommandations pour le budget f\u00e9d\u00e9ral de 2026 \u2022 Canadian Crafts Federation","description":"Pour l\u2019ann\u00e9e 2026, la F\u00e9d\u00e9ration canadienne des m\u00e9tiers d\u2019art (FCMA\/CCF), en collaboration avec les conseils provinciaux des m\u00e9tiers d\u2019art et organismes affili\u00e9s, se pr\u00e9sente ici \u00e0 titre de f\u00e9d\u00e9ration d\u2019organisations afin d\u2019\u00e9laborer ses Recommandations pr\u00e9-budg\u00e9taires destin\u00e9es au ministre f\u00e9d\u00e9ral des Finances. L\u2019objectif de la FCMA\/CCF est de se faire entendre \u00e0 travers une voix unie","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/canadiancraftsfederation.ca\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/canadiancraftsfederation.ca\/fr\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\/#breadcrumblist"},"author":{"@id":"https:\/\/canadiancraftsfederation.ca\/fr\/author\/lauren-polchies\/#author"},"creator":{"@id":"https:\/\/canadiancraftsfederation.ca\/fr\/author\/lauren-polchies\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/canadiancraftsfederation.ca\/wp-content\/uploads\/2026\/07\/banner-page2-scaled.png","@id":"https:\/\/canadiancraftsfederation.ca\/fr\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\/#mainImage","width":2560,"height":830},"primaryImageOfPage":{"@id":"https:\/\/canadiancraftsfederation.ca\/fr\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\/#mainImage"},"datePublished":"2026-07-15T11:38:06-03:00","dateModified":"2026-07-15T11:51:30-03:00"},{"@type":"WebSite","@id":"https:\/\/canadiancraftsfederation.ca\/fr\/#website","url":"https:\/\/canadiancraftsfederation.ca\/fr\/","name":"Canadian Crafts Federation | F\u00e9d\u00e9ration canadiennes des m\u00e9tiers d'art","alternateName":"CCF\/FCMA","description":"National Arts Service Organization","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/canadiancraftsfederation.ca\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Canadian Crafts Federation \u2022 National Arts Service Organization","og:type":"article","og:title":"Pour un meilleur support des m\u00e9tiers d\u2019art : Recommandations pour le budget f\u00e9d\u00e9ral de 2026 \u2022 Canadian Crafts Federation","og:description":"Pour l\u2019ann\u00e9e 2026, la F\u00e9d\u00e9ration canadienne des m\u00e9tiers d\u2019art (FCMA\/CCF), en collaboration avec les conseils provinciaux des m\u00e9tiers d\u2019art et organismes affili\u00e9s, se pr\u00e9sente ici \u00e0 titre de f\u00e9d\u00e9ration d\u2019organisations afin d\u2019\u00e9laborer ses Recommandations pr\u00e9-budg\u00e9taires destin\u00e9es au ministre f\u00e9d\u00e9ral des Finances. L\u2019objectif de la FCMA\/CCF est de se faire entendre \u00e0 travers une voix unie","og:url":"https:\/\/canadiancraftsfederation.ca\/fr\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\/","og:image":"https:\/\/canadiancraftsfederation.ca\/wp-content\/uploads\/2023\/07\/Form-Banner-2023.png","og:image:secure_url":"https:\/\/canadiancraftsfederation.ca\/wp-content\/uploads\/2023\/07\/Form-Banner-2023.png","og:image:width":6667,"og:image:height":1667,"article:published_time":"2026-07-15T14:38:06+00:00","article:modified_time":"2026-07-15T14:51:30+00:00","article:publisher":"https:\/\/facebook.com\/ccffcma","twitter:card":"summary_large_image","twitter:site":"@ccffcma","twitter:title":"Pour un meilleur support des m\u00e9tiers d\u2019art : Recommandations pour le budget f\u00e9d\u00e9ral de 2026 \u2022 Canadian Crafts Federation","twitter:description":"Pour l\u2019ann\u00e9e 2026, la F\u00e9d\u00e9ration canadienne des m\u00e9tiers d\u2019art (FCMA\/CCF), en collaboration avec les conseils provinciaux des m\u00e9tiers d\u2019art et organismes affili\u00e9s, se pr\u00e9sente ici \u00e0 titre de f\u00e9d\u00e9ration d\u2019organisations afin d\u2019\u00e9laborer ses Recommandations pr\u00e9-budg\u00e9taires destin\u00e9es au ministre f\u00e9d\u00e9ral des Finances. L\u2019objectif de la FCMA\/CCF est de se faire entendre \u00e0 travers une voix unie","twitter:creator":"@ccffcma","twitter:image":"https:\/\/canadiancraftsfederation.ca\/wp-content\/uploads\/2023\/07\/Form-Banner-2023.png"},"aioseo_meta_data":{"post_id":"11467","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":{"subject":"","preview":"","content":""},"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-07-15 12:54:14","updated":"2026-07-15 15:31:12","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/canadiancraftsfederation.ca\/fr\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/canadiancraftsfederation.ca\/fr\/category\/non-classifiee\/\" title=\"Non classifi\u00e9(e)\">Non classifi\u00e9(e)<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPour un meilleur support des m\u00e9tiers d\u2019art : Recommandations pour le budget f\u00e9d\u00e9ral de 2026\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/canadiancraftsfederation.ca\/fr\/"},{"label":"Non classifi\u00e9(e)","link":"https:\/\/canadiancraftsfederation.ca\/fr\/category\/non-classifiee\/"},{"label":"Pour un meilleur support des m\u00e9tiers d&rsquo;art : Recommandations pour le budget f\u00e9d\u00e9ral de 2026","link":"https:\/\/canadiancraftsfederation.ca\/fr\/pour-un-meilleur-support-des-metiers-dart-recommandations-pour-le-budget-federal-de-2026\/"}],"_links":{"self":[{"href":"https:\/\/canadiancraftsfederation.ca\/fr\/wp-json\/wp\/v2\/posts\/11467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canadiancraftsfederation.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canadiancraftsfederation.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canadiancraftsfederation.ca\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/canadiancraftsfederation.ca\/fr\/wp-json\/wp\/v2\/comments?post=11467"}],"version-history":[{"count":3,"href":"https:\/\/canadiancraftsfederation.ca\/fr\/wp-json\/wp\/v2\/posts\/11467\/revisions"}],"predecessor-version":[{"id":11482,"href":"https:\/\/canadiancraftsfederation.ca\/fr\/wp-json\/wp\/v2\/posts\/11467\/revisions\/11482"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canadiancraftsfederation.ca\/fr\/wp-json\/wp\/v2\/media\/11479"}],"wp:attachment":[{"href":"https:\/\/canadiancraftsfederation.ca\/fr\/wp-json\/wp\/v2\/media?parent=11467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canadiancraftsfederation.ca\/fr\/wp-json\/wp\/v2\/categories?post=11467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canadiancraftsfederation.ca\/fr\/wp-json\/wp\/v2\/tags?post=11467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}